{"id":7,"date":"2026-01-20T10:13:58","date_gmt":"2026-01-20T10:13:58","guid":{"rendered":"https:\/\/ortopedie-sopon.ro\/?page_id=7"},"modified":"2026-04-14T08:51:52","modified_gmt":"2026-04-14T08:51:52","slug":"home","status":"publish","type":"page","link":"https:\/\/ortopedie-sopon.ro\/","title":{"rendered":"Home"},"content":{"rendered":"<div class=\"oxy-container-7-104 oxy-container container-1\"><div class=\"oxy-container-7-105 oxy-container container-19\" data-entrance=\"slideLeft\"><div class=\"oxy-container-7-106 oxy-container container-20\"><span class=\"oxy-text-7-113 oxy-text text-4\" data-entrance=\"slideRight\">\n<span class=\"text-blue\">Ortopedie<\/span> modern\u0103 pentru mobilitate f\u0103r\u0103 durere\n<\/span><div class=\"bde-button-7-213 bde-button button-programeaza\">\n    \n                        \n                        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--custom bde-button__button\" href=\"https:\/\/ortopedie-sopon.ro\/index.php\/contact\/\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Programeaz\u0103 o consulta\u021bie<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div><\/div><div class=\"oxy-container-7-107 oxy-container container-36\"><img decoding=\"async\" class=\"oxy-image-7-108 oxy-image image-5\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/Dr-Sopon-8-scaled.png\" loading=\"lazy\" srcset=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/Dr-Sopon-8-scaled.png 1707w, https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/Dr-Sopon-8-200x300.png 200w, https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/Dr-Sopon-8-683x1024.png 683w, https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/Dr-Sopon-8-768x1152.png 768w, https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/Dr-Sopon-8-1024x1536.png 1024w, https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/Dr-Sopon-8-1365x2048.png 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" data-entrance=\"slideRight\"><\/div><\/div><div class=\"oxy-container-7-114 oxy-container container-22\"><div class=\"bde-columns-7-117 bde-columns columns-2\"><div class=\"bde-column-7-118 bde-column\">\n  \n  \n\t\n\n\n\n<div class=\"oxy-container-7-134 oxy-container container-24\"><img decoding=\"async\" class=\"oxy-image-7-147 oxy-image image-6\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/streamline-ultimate_medical-instrument-ambulance-bed.svg\" loading=\"lazy\" sizes=\"(max-width: 62px) 100vw, 62px\"><img decoding=\"async\" class=\"oxy-image-7-155 oxy-image image-for-hover\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/svgviewer-output-3.svg\" loading=\"lazy\" sizes=\"(max-width: 62px) 100vw, 62px\"><div class=\"oxy-container-7-136 oxy-container container-23\"><div class=\"oxy-text-7-137 oxy-text text-5\">\nActe necesare la internare\n<\/div><div class=\"bde-button-7-214 bde-button scr-buton-acte\">\n    \n                        \n                        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--custom bde-button__button\" href=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/04\/Acte-necesare-la-internare.pdf\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Apas\u0103 aici<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div><\/div><div class=\"bde-button-7-212 bde-button scr-button-home\">\n    \n                        \n                        \n    \n    \n    \n    \n            \n            <button type=\"button\" class=\"button-atom button-atom--custom bde-button__button\"  >\n    \n        <span class=\"button-atom__text\">Citeste mai mult<\/span>\n\n        \n        \n            <\/button>\n    \n\n\n<\/div><\/div>\n<\/div><div class=\"bde-column-7-119 bde-column column-2\">\n  \n  \n\t\n\n\n\n<div class=\"oxy-container-7-123 oxy-container container-24\"><img decoding=\"async\" class=\"oxy-image-7-216 oxy-image image-6\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/streamline-ultimate_medical-specialty-knee-1.svg\" loading=\"lazy\" sizes=\"(max-width: 62px) 100vw, 62px\"><img decoding=\"async\" class=\"oxy-image-7-154 oxy-image image-for-hover\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/svgviewer-output-2.svg\" loading=\"lazy\" sizes=\"(max-width: 62px) 100vw, 62px\"><div class=\"oxy-container-7-130 oxy-container container-23\"><div class=\"oxy-text-7-215 oxy-text text-5\">\nActe necesare la internare protez\u0103\n<\/div><div class=\"bde-button-7-217 bde-button scr-buton-acte\">\n    \n                        \n                        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--custom bde-button__button\" href=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/04\/Acte-necesare-la-internare-proteza.pdf\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Apas\u0103 aici<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div><\/div><\/div>\n<\/div><div class=\"bde-column-7-120 bde-column column-1\">\n  \n  \n\t\n\n\n\n<div class=\"oxy-container-7-140 oxy-container container-24\"><img decoding=\"async\" class=\"oxy-image-7-133 oxy-image image-6\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/uil_medical.svg\" loading=\"lazy\" sizes=\"(max-width: 62px) 100vw, 62px\"><img decoding=\"async\" class=\"oxy-image-7-153 oxy-image image-for-hover\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/svgviewer-output-1.svg\" loading=\"lazy\" sizes=\"(max-width: 62px) 100vw, 62px\"><div class=\"oxy-container-7-142 oxy-container container-23\"><div class=\"oxy-text-7-143 oxy-text text-5\">\nScrisoare medical\u0103\n<\/div><div class=\"bde-button-7-219 bde-button scr-buton-acte\">\n    \n                        \n                        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--custom bde-button__button\" href=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/04\/Scrisoare-medicala.pdf\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Apas\u0103 aici<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div><\/div><\/div>\n<\/div><div class=\"bde-column-7-121 bde-column\">\n  \n  \n\t\n\n\n\n<div class=\"oxy-container-7-146 oxy-container container-24\"><img decoding=\"async\" class=\"oxy-image-7-135 oxy-image image-6\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/svgviewer-output.svg\" loading=\"lazy\" sizes=\"(max-width: 62px) 100vw, 62px\"><img decoding=\"async\" class=\"oxy-image-7-152 oxy-image image-for-hover\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/jam_medical.svg\" loading=\"lazy\" sizes=\"(max-width: 62px) 100vw, 62px\"><div class=\"oxy-container-7-148 oxy-container container-23\"><div class=\"oxy-text-7-149 oxy-text text-5\">\nAfec\u021biuni de Ortopedie \u0219i Traumatologie\n<\/div><div class=\"bde-button-7-220 bde-button scr-buton-acte\">\n    \n                        \n                        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--custom bde-button__button\" href=\"https:\/\/ortopedie-sopon.ro\/index.php\/servicii\/\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Apas\u0103 aici<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div><\/div><\/div>\n<\/div><\/div><\/div><div class=\"oxy-container-7-116 oxy-container container-25\"><div class=\"oxy-text-7-156 oxy-text text-7\" data-entrance=\"slideLeft\">\nGrij\u0103 personalizat\u0103 pentru fiecare pacient\n<\/div><div class=\"oxy-container-7-157 oxy-container container-31\"><div class=\"oxy-container-7-175 oxy-container container-34\"><div class=\"oxy-container-7-178 oxy-container container-33\"><img decoding=\"async\" class=\"oxy-image-7-183 oxy-image image-9\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/jam_medical.svg\" loading=\"lazy\" sizes=\"(max-width: 62px) 100vw, 62px\"><div class=\"oxy-container-7-184 oxy-container container-35\"><div class=\"oxy-text-7-185 oxy-text text-11\">\nExperien\u021b\u0103 \u0219i profesionalism\n<\/div><div class=\"oxy-text-7-186 oxy-text text-12\">\nAbordare medical\u0103 bazat\u0103 pe experien\u021b\u0103 \u0219i aten\u021bie la detalii.\n<\/div><\/div><\/div><div class=\"oxy-container-7-179 oxy-container container-33\"><img decoding=\"async\" class=\"oxy-image-7-187 oxy-image image-9\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/jam_medical.svg\" loading=\"lazy\" sizes=\"(max-width: 62px) 100vw, 62px\"><div class=\"oxy-container-7-188 oxy-container container-35\"><div class=\"oxy-text-7-189 oxy-text text-11\">\nRecuperare ghidat\u0103\n<\/div><div class=\"oxy-text-7-190 oxy-text text-12\">\nSuport pe tot parcursul tratamentului \u0219i recuper\u0103rii.\n<\/div><\/div><\/div><\/div><div class=\"oxy-container-7-181 oxy-container container-32\" data-entrance=\"zoomIn\"><\/div><div class=\"oxy-container-7-177 oxy-container container-34\"><div class=\"oxy-container-7-176 oxy-container container-33\"><img decoding=\"async\" class=\"oxy-image-7-197 oxy-image image-9\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/jam_medical.svg\" loading=\"lazy\" sizes=\"(max-width: 62px) 100vw, 62px\"><div class=\"oxy-container-7-191 oxy-container container-35\"><div class=\"oxy-text-7-192 oxy-text text-11\">\nConsult personalizat\n<\/div><div class=\"oxy-text-7-193 oxy-text text-12\">\nFiecare pacient este evaluat individual, f\u0103r\u0103 solu\u021bii standard.\n<\/div><\/div><\/div><div class=\"oxy-container-7-180 oxy-container container-33\"><img decoding=\"async\" class=\"oxy-image-7-198 oxy-image image-9\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/jam_medical.svg\" loading=\"lazy\" sizes=\"(max-width: 62px) 100vw, 62px\"><div class=\"oxy-container-7-194 oxy-container container-35\"><div class=\"oxy-text-7-195 oxy-text text-11\">\nComunicare clar\u0103\n<\/div><div class=\"oxy-text-7-196 oxy-text text-12\">\nExplica\u021bii simple \u0219i transparente pentru fiecare etap\u0103.\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"oxy-container-7-115 oxy-container container-26\" data-entrance=\"slideLeft\"><div class=\"oxy-container-7-158 oxy-container container-27\"><\/div><div class=\"oxy-container-7-159 oxy-container container-29\"><div class=\"oxy-text-7-161 oxy-text text-8\">\nDr. Sopon Mircea Ciprian\n<\/div><div class=\"oxy-text-7-162 oxy-text text-9\">\nDr. Sopon Mircea Ciprian este medic primar \u00een Ortopedie-Traumatologie, cu o experien\u021b\u0103 vast\u0103 \u00een diagnosticarea \u0219i tratamentul afec\u021biunilor aparatului locomotor.\n<\/div><div class=\"oxy-container-7-163 oxy-container container-30\"><div class=\"oxy-container-7-164 oxy-container container-28\"><img decoding=\"async\" class=\"oxy-image-7-167 oxy-image image-8\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/ion_medical-sharp.svg\" loading=\"lazy\" sizes=\"(max-width: 31px) 100vw, 31px\"><div class=\"oxy-text-7-168 oxy-text text-10\">\nFormare medical\u0103\n<\/div><\/div><div class=\"oxy-container-7-172 oxy-container container-28\"><img decoding=\"async\" class=\"oxy-image-7-173 oxy-image image-8\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/ion_medical-sharp.svg\" loading=\"lazy\" sizes=\"(max-width: 31px) 100vw, 31px\"><div class=\"oxy-text-7-174 oxy-text text-10\">\nReziden\u021biat \u0219i specializare\n<\/div><\/div><div class=\"oxy-container-7-169 oxy-container container-28\"><img decoding=\"async\" class=\"oxy-image-7-170 oxy-image image-8\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/ion_medical-sharp.svg\" loading=\"lazy\" sizes=\"(max-width: 31px) 100vw, 31px\"><div class=\"oxy-text-7-171 oxy-text text-10\">\nExperien\u021b\u0103 profesional\u0103\n<\/div><\/div><div class=\"oxy-container-7-221 oxy-container container-28\"><img decoding=\"async\" class=\"oxy-image-7-222 oxy-image image-8\" src=\"https:\/\/ortopedie-sopon.ro\/wp-content\/uploads\/2026\/01\/ion_medical-sharp.svg\" loading=\"lazy\" sizes=\"(max-width: 31px) 100vw, 31px\"><div class=\"oxy-text-7-223 oxy-text text-10\">\nActivitate academic\u0103\n<\/div><\/div><\/div><\/div><\/div><div class=\"oxy-container-202-100-202-1 oxy-container container-37 oxy-container-202-100\"><div class=\"oxy-container-202-101-202-1 oxy-container container-39 oxy-container-202-101\"><div class=\"oxy-container-202-102-202-1 oxy-container container-38 oxy-container-202-102\"><div class=\"oxy-text-202-103-202-1 oxy-text text-13 oxy-text-202-103\" data-entrance=\"slideLeft\">\nContacteaz\u0103-ne pentru o consulta\u021bie de specialitate\n<\/div><div class=\"bde-button-202-104-202-1 bde-button button-4 bde-button-202-104\">\n    \n                        \n                        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--custom bde-button__button\" href=\"https:\/\/ortopedie-sopon.ro\/index.php\/contact\/\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Contacteaz\u0103-m\u0103<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Ortopedie modern\u0103 pentru mobilitate f\u0103r\u0103 durere Programeaz\u0103 o consulta\u021bie Acte necesare la internare Apas\u0103 aici Citeste mai mult Acte necesare la internare protez\u0103 Apas\u0103 aici Scrisoare medical\u0103 Apas\u0103 aici Afec\u021biuni de Ortopedie \u0219i Traumatologie Apas\u0103 aici Grij\u0103 personalizat\u0103 pentru fiecare pacient Experien\u021b\u0103 \u0219i profesionalism Abordare medical\u0103 bazat\u0103 pe experien\u021b\u0103 \u0219i aten\u021bie la detalii. Recuperare ghidat\u0103 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_oxygen_hide_in_design_set":false,"_oxygen_tags":"","footnotes":""},"class_list":["post-7","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ortopedie-sopon.ro\/index.php\/wp-json\/wp\/v2\/pages\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ortopedie-sopon.ro\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ortopedie-sopon.ro\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ortopedie-sopon.ro\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ortopedie-sopon.ro\/index.php\/wp-json\/wp\/v2\/comments?post=7"}],"version-history":[{"count":105,"href":"https:\/\/ortopedie-sopon.ro\/index.php\/wp-json\/wp\/v2\/pages\/7\/revisions"}],"predecessor-version":[{"id":611,"href":"https:\/\/ortopedie-sopon.ro\/index.php\/wp-json\/wp\/v2\/pages\/7\/revisions\/611"}],"wp:attachment":[{"href":"https:\/\/ortopedie-sopon.ro\/index.php\/wp-json\/wp\/v2\/media?parent=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}